{"id":541,"date":"2018-11-27T09:17:08","date_gmt":"2018-11-27T09:17:08","guid":{"rendered":"https:\/\/duophebus.com\/about\/"},"modified":"2024-10-19T11:18:26","modified_gmt":"2024-10-19T11:18:26","slug":"a-propos","status":"publish","type":"page","link":"https:\/\/duophebus.com\/en\/a-propos\/","title":{"rendered":"About us"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"541\" class=\"elementor elementor-541\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6737de5 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6737de5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ba06399\" data-id=\"ba06399\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-82b2a0b elementor-widget elementor-widget-image\" data-id=\"82b2a0b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"5731\" height=\"2968\" src=\"https:\/\/duophebus.com\/wp-content\/uploads\/2021\/12\/Helene-Martin-62bis.jpg\" class=\"attachment-full size-full wp-image-1567\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5c40d7b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5c40d7b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2ebbf9c\" data-id=\"2ebbf9c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe195c7 elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"fe195c7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">The duo<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-05e05a5 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-heading\" data-id=\"05e05a5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">The duo<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc051dd elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"dc051dd\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5f497e elementor-widget elementor-widget-text-editor\" data-id=\"e5f497e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><b><i>Phebus is one of the numerous names of Apollo, a solar god and protector of the arts in the Greco-Roman world.<\/i><\/b><\/p><p>Tous deux musiciens titulaires au sein de l\u2019Op\u00e9ra Royal de Wallonie (Li\u00e8ge), nous avons ressenti l\u2019envie d\u2019explorer ensemble de nouveaux paysages musicaux\u00a0et avons form\u00e9 un duo violon\/alto &#8211; percussions, plac\u00e9 sous le double signe de la diversit\u00e9 et de la d\u00e9couverte.<\/p><p>Lors de nos concerts, nous naviguons entre les \u0153uvres des grands compositeurs du pass\u00e9 (jou\u00e9es sous forme de transcriptions) et les pi\u00e8ces du r\u00e9pertoire contemporain \u00e9crites sp\u00e9cifiquement pour cette formation.<\/p><p align=\"justify\">Fortement engag\u00e9 dans la cr\u00e9ation musicale, notre duo a travaill\u00e9 avec des compositeurs de renomm\u00e9e internationale et a notamment command\u00e9 des \u0153uvres \u00e0 Fran\u00e7ois Narboni (FR), Daniel Capelletti (BE), Jean-Marie Rens (BE), Anders Koppel (DK), &#8230;<\/p><p align=\"justify\">Notre premier album \u00ab\u00a0Convergences\u00a0\u00bb, r\u00e9alis\u00e9 avec le label li\u00e9geois Homerecords Studio, est sorti le 8 septembre 2023. Ce premier opus, repr\u00e9sentatif de notre travail, inclut plusieurs de nos transcriptions ainsi que les deux pi\u00e8ces command\u00e9es \u00e0 Fran\u00e7ois Narboni et \u00e0 Anders Koppel.<\/p><p align=\"justify\">Pr\u00e9sent sur la sc\u00e8ne des concours internationaux, notre duo a remport\u00e9 un 2e prix \u00e0 la \u00ab\u00a0Malopolska International Music Competition\u00a0\u00bb (Pologne), un 3e prix \u00e0 la \u00ab\u00a0France Music Competition\u00a0\u00bb ainsi qu\u2019un 2e prix \u00e0 la \u00ab\u00a0Vrsac Music in the Vineyards Competition\u00a0\u00bb (Serbie).<\/p><p><style type=\"text\/css\">p { margin-bottom: 0.25cm; line-height: 115%; background: transparent }<\/style><\/p><p>Notre duo est sponsoris\u00e9 par l&rsquo;entreprise fran\u00e7aise de cr\u00e9ation d&rsquo;instruments \u00e0 percussions Bergerault.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e5fdae0\" data-id=\"e5fdae0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e85dabe elementor-widget elementor-widget-image\" data-id=\"e85dabe\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"5760\" height=\"3840\" src=\"https:\/\/duophebus.com\/wp-content\/uploads\/2021\/11\/Helene-Martin-28.jpg\" class=\"attachment-full size-full wp-image-1118\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb33174 elementor-mobile-align-center elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"cb33174\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/duophebus.com\/en\/medias\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Photos et Vid\u00e9os<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7f7c94 elementor-mobile-align-center elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"c7f7c94\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/duophebus.com\/en\/repertoire\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Notre r\u00e9pertoire<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-53f3320 elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"53f3320\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-be4a8b9\" data-id=\"be4a8b9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-efdb485 elementor-widget elementor-widget-spacer\" data-id=\"efdb485\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0459207 elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"0459207\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/duophebus.com\/en\/medias\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Photos et Vid\u00e9os<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e92456d elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"e92456d\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/duophebus.com\/en\/repertoire\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Notre r\u00e9pertoire<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e90a943 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e90a943\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2126f92\" data-id=\"2126f92\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43a347a elementor-widget elementor-widget-heading\" data-id=\"43a347a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Violon\/Alto<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7818b1a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7818b1a\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92bbe33 elementor-widget elementor-widget-heading\" data-id=\"92bbe33\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">H\u00e9l\u00e8ne Petit <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25b80b4 elementor-widget elementor-widget-image\" data-id=\"25b80b4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/duophebus.com\/wp-content\/uploads\/2021\/07\/Helene-Martin-6.jpg\" class=\"attachment-medium size-medium wp-image-1013\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8f9f49 elementor-widget elementor-widget-text-editor\" data-id=\"d8f9f49\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Born in 1989 in Thionville (France), H\u00e9l\u00e8ne Petit began studying the violin at the age of 7 with Elisabeth Bauer.<\/p><p>She continued her musical education at the Conservatoire R\u00e9gional de Metz with Carole Bru\u00e8re-Garbarg, and then joined the violin classes of Christophe Poiget and Annick Roussin at the Superior Pole of Paris in 2011.<\/p><p>There, she obtained a National Superior Diploma of Professional Musician (DNSPM), a State Diploma (DE) to be able to teach violin and a Bachelor of musicology at the Paris-Sorbonne University.<\/p><p>She continued her studies with Marie-Annick Nicolas at the Haute Ecole de Musique de Gen\u00e8ve, where she obtained a Master of Concert in 2015.<\/p><p>She is regularly invited to play with the orchestra of the National Opera of Lorraine (Nancy), the Symphonic Orchestra of Mulhouse, the National Orchestra of Metz and has also participated in some projects with the orchestra \u00ab\u00a0Les Si\u00e8cles\u00a0\u00bb.<\/p><p>Since February 2018, H\u00e9l\u00e8ne is a permanent violonist in the orchestra of the Royal Opera of Li\u00e8ge. A chamber music enthusiast, H\u00e9l\u00e8ne takes part in numerous projects besides her activities at the Opera\u00a0: in 2018, she became a member of the Chamber Orchestra of Li\u00e8ge and in 2020 she formed the Khr\u00f4ma Quartet with Nina Poskin, Fran\u00e7ois-Jean Yzambart and Fr\u00e9d\u00e9ric Preusser.<\/p><p>Tomb\u00e9e sous le charme de l&rsquo;alto en 2021, H\u00e9l\u00e8ne pratique \u00e9galement cet instrument dans le cadre du Duo Ph\u00e9bus.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1f55312\" data-id=\"1f55312\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-951c6f6 elementor-widget elementor-widget-heading\" data-id=\"951c6f6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Marimba<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e1083c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0e1083c\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-061f997 elementor-widget elementor-widget-heading\" data-id=\"061f997\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Martin Descamps <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fa2282 elementor-widget elementor-widget-image\" data-id=\"2fa2282\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/duophebus.com\/wp-content\/uploads\/2021\/07\/Helene-Martin-16.jpg\" class=\"attachment-medium size-medium wp-image-771\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49dce2e elementor-widget elementor-widget-text-editor\" data-id=\"49dce2e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Born in 1996 in Namur (Belgium), Martin Descamps began percussion lessons at the age of 5 at the Conservatoire Lucien Robert in Tamines with Thierry Lapierre.<\/p>\n<p>En 2010, il int\u00e8gre la classe de percussions de Jessica Ryckewaert et Claude Podgornik \u00e0 l&rsquo;Institut Sup\u00e9rieur de Musique et de P\u00e9dagogie de Namur (IMEP) dans le cadre du syst\u00e8me \u00ab\u00a0Jeunes Talents\u00a0\u00bb. Il re\u00e7oit un \u00ab\u00a01er prix\u00a0\u00bb au concours Dexia Classics en 2011 et est invit\u00e9 quelques mois plus tard \u00e0 jouer le \u00ab\u00a0Concerto pour marimba\u00a0\u00bb d&rsquo;Emmanuel S\u00e9journ\u00e9 avec l&rsquo;Orchestre Aria au Th\u00e9\u00e2tre Royal de la Monnaie (Bruxelles).<\/p>\n<p>Nomm\u00e9 \u00ab\u00a0Namurois de l&rsquo;ann\u00e9e\u00a0\u00bb dans la cat\u00e9gorie \u00ab\u00a0Jeune Talent\u00a0\u00bb en 2013, il entame une licence d&rsquo;interpr\u00e9tation musicale en percussions \u00e0 l&rsquo;IMEP.<\/p>\n<p>The following year, he continued his course at the Conservatoire Sup\u00e9rieur de Strasbourg with Emmanuel S\u00e9journ\u00e9, St\u00e9phane Fougeroux and Denis Riedinger. During this period, he was also invited to play with the Philharmonic Orchestra of Strasbourg.<\/p>\n<p>Since August 2015, Martin holds the position of 1st Solo Percussionnist \/ 2nd Timpanist in the orchestra of the Royal Opera of Li\u00e8ge. He is regularly invited to play with other orchestras such as the Royal Philharmonic Orchestra of Li\u00e8ge and the orchestra of the Dortmund Opera (Germany). <\/p>\n<p>\u00c9galement pr\u00e9sent sur la sc\u00e8ne des concours solistes internationaux, Martin a re\u00e7u un \u00ab\u00a02e prix\u00a0\u00bb \u00e0 la Swiss Percussion Competition en septembre 2022, un \u00ab\u00a02e prix\u00a0\u00bb \u00e0 l&rsquo;Italy Percussive Arts Society Competition (cat. Vibraphone) en novembre 2022 ainsi qu&rsquo;un \u00ab\u00a01er prix \u00e0 l&rsquo;unanimit\u00e9\u00a0\u00bb doubl\u00e9 d&rsquo;un \u00ab\u00a0Prix d&rsquo;Honneur\u00a0\u00bb \u00e0 la France Music Competition en d\u00e9cembre 2022.<\/p>\n<p>Investi dans la transmission de son art, il est depuis septembre 2024 enseignant de musique de chambre au Conservatoire Sup\u00e9rieur de Mons (Arts\u00b2).<br><\/p>\n<p><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2942262 elementor-widget elementor-widget-text-editor\" data-id=\"2942262\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Le Duo Le Duo Ph\u00e9bus est une des \u00e9pith\u00e8tes d\u2019Apollon, dieu solaire et protecteur des arts dans le monde gr\u00e9co-romain. Tous deux musiciens titulaires au sein de l\u2019Op\u00e9ra Royal de Wallonie (Li\u00e8ge), nous avons ressenti l\u2019envie d\u2019explorer ensemble de nouveaux paysages musicaux\u00a0et avons form\u00e9 un duo violon\/alto &#8211; percussions, plac\u00e9 sous le double signe de [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-541","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c0 propos - Duo Phebus<\/title>\n<meta name=\"description\" content=\"Duo violon-marimba constitu\u00e9 par deux musiciens de l&#039;Op\u00e9ra Royal de Wallonie. Ils revisitent des oeuvres du pass\u00e9 et interpr\u00e8tent ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/duophebus.com\/en\/a-propos\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c0 propos - Duo Phebus\" \/>\n<meta property=\"og:description\" content=\"Duo violon-marimba constitu\u00e9 par deux musiciens de l&#039;Op\u00e9ra Royal de Wallonie. Ils revisitent des oeuvres du pass\u00e9 et interpr\u00e8tent ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/duophebus.com\/en\/a-propos\/\" \/>\n<meta property=\"og:site_name\" content=\"Duo Phebus\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Duo-Ph%c3%a9bus-100438209154859\/?ref=page_internal\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-19T11:18:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/duophebus.com\/wp-content\/uploads\/2021\/12\/Helene-Martin-62bis.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"530\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/duophebus.com\\\/a-propos\\\/\",\"url\":\"https:\\\/\\\/duophebus.com\\\/a-propos\\\/\",\"name\":\"\u00c0 propos - Duo Phebus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/duophebus.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/duophebus.com\\\/a-propos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/duophebus.com\\\/a-propos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/duophebus.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Helene-Martin-62bis.jpg\",\"datePublished\":\"2018-11-27T09:17:08+00:00\",\"dateModified\":\"2024-10-19T11:18:26+00:00\",\"description\":\"Duo violon-marimba constitu\u00e9 par deux musiciens de l'Op\u00e9ra Royal de Wallonie. Ils revisitent des oeuvres du pass\u00e9 et interpr\u00e8tent ...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/duophebus.com\\\/a-propos\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/duophebus.com\\\/a-propos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/duophebus.com\\\/a-propos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/duophebus.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Helene-Martin-62bis.jpg\",\"contentUrl\":\"https:\\\/\\\/duophebus.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Helene-Martin-62bis.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/duophebus.com\\\/a-propos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/duophebus.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c0 propos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/duophebus.com\\\/#website\",\"url\":\"https:\\\/\\\/duophebus.com\\\/\",\"name\":\"Duo Phebus\",\"description\":\"Duo Phebus Official Website\",\"publisher\":{\"@id\":\"https:\\\/\\\/duophebus.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/duophebus.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/duophebus.com\\\/#organization\",\"name\":\"Duo Ph\u00e9bus\",\"url\":\"https:\\\/\\\/duophebus.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/duophebus.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/duophebus.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/LogoMakr-2g0SR2.png\",\"contentUrl\":\"https:\\\/\\\/duophebus.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/LogoMakr-2g0SR2.png\",\"width\":300,\"height\":169,\"caption\":\"Duo Ph\u00e9bus\"},\"image\":{\"@id\":\"https:\\\/\\\/duophebus.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Duo-Ph\u00e9bus-100438209154859\\\/?ref=page_internal\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCI23FKcBEtQkU47XKdf0mqQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c0 propos - Duo Phebus","description":"Duo violon-marimba constitu\u00e9 par deux musiciens de l'Op\u00e9ra Royal de Wallonie. Ils revisitent des oeuvres du pass\u00e9 et interpr\u00e8tent ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/duophebus.com\/en\/a-propos\/","og_locale":"en_GB","og_type":"article","og_title":"\u00c0 propos - Duo Phebus","og_description":"Duo violon-marimba constitu\u00e9 par deux musiciens de l'Op\u00e9ra Royal de Wallonie. Ils revisitent des oeuvres du pass\u00e9 et interpr\u00e8tent ...","og_url":"https:\/\/duophebus.com\/en\/a-propos\/","og_site_name":"Duo Phebus","article_publisher":"https:\/\/www.facebook.com\/Duo-Ph%c3%a9bus-100438209154859\/?ref=page_internal","article_modified_time":"2024-10-19T11:18:26+00:00","og_image":[{"url":"https:\/\/duophebus.com\/wp-content\/uploads\/2021\/12\/Helene-Martin-62bis.jpg","width":1024,"height":530,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/duophebus.com\/a-propos\/","url":"https:\/\/duophebus.com\/a-propos\/","name":"\u00c0 propos - Duo Phebus","isPartOf":{"@id":"https:\/\/duophebus.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/duophebus.com\/a-propos\/#primaryimage"},"image":{"@id":"https:\/\/duophebus.com\/a-propos\/#primaryimage"},"thumbnailUrl":"https:\/\/duophebus.com\/wp-content\/uploads\/2021\/12\/Helene-Martin-62bis.jpg","datePublished":"2018-11-27T09:17:08+00:00","dateModified":"2024-10-19T11:18:26+00:00","description":"Duo violon-marimba constitu\u00e9 par deux musiciens de l'Op\u00e9ra Royal de Wallonie. Ils revisitent des oeuvres du pass\u00e9 et interpr\u00e8tent ...","breadcrumb":{"@id":"https:\/\/duophebus.com\/a-propos\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/duophebus.com\/a-propos\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/duophebus.com\/a-propos\/#primaryimage","url":"https:\/\/duophebus.com\/wp-content\/uploads\/2021\/12\/Helene-Martin-62bis.jpg","contentUrl":"https:\/\/duophebus.com\/wp-content\/uploads\/2021\/12\/Helene-Martin-62bis.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/duophebus.com\/a-propos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/duophebus.com\/"},{"@type":"ListItem","position":2,"name":"\u00c0 propos"}]},{"@type":"WebSite","@id":"https:\/\/duophebus.com\/#website","url":"https:\/\/duophebus.com\/","name":"Duo Phebus","description":"Duo Phebus Official Website","publisher":{"@id":"https:\/\/duophebus.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/duophebus.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/duophebus.com\/#organization","name":"Duo Ph\u00e9bus","url":"https:\/\/duophebus.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/duophebus.com\/#\/schema\/logo\/image\/","url":"https:\/\/duophebus.com\/wp-content\/uploads\/2021\/11\/LogoMakr-2g0SR2.png","contentUrl":"https:\/\/duophebus.com\/wp-content\/uploads\/2021\/11\/LogoMakr-2g0SR2.png","width":300,"height":169,"caption":"Duo Ph\u00e9bus"},"image":{"@id":"https:\/\/duophebus.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Duo-Ph\u00e9bus-100438209154859\/?ref=page_internal","https:\/\/www.youtube.com\/channel\/UCI23FKcBEtQkU47XKdf0mqQ"]}]}},"_links":{"self":[{"href":"https:\/\/duophebus.com\/en\/wp-json\/wp\/v2\/pages\/541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/duophebus.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/duophebus.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/duophebus.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/duophebus.com\/en\/wp-json\/wp\/v2\/comments?post=541"}],"version-history":[{"count":295,"href":"https:\/\/duophebus.com\/en\/wp-json\/wp\/v2\/pages\/541\/revisions"}],"predecessor-version":[{"id":2320,"href":"https:\/\/duophebus.com\/en\/wp-json\/wp\/v2\/pages\/541\/revisions\/2320"}],"wp:attachment":[{"href":"https:\/\/duophebus.com\/en\/wp-json\/wp\/v2\/media?parent=541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}